{"id":196,"count":4,"description":"","link":"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/","name":"Generative AI","slug":"generative-ai","taxonomy":"category","parent":8,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Generative AI Archives - Tech Blogs<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Generative AI Archives - Tech Blogs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/\" \/>\n<meta property=\"og:site_name\" content=\"Tech Blogs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.infolks.info\\\/blog\\\/category\\\/artificial-intelligence\\\/generative-ai\\\/\",\"url\":\"https:\\\/\\\/www.infolks.info\\\/blog\\\/category\\\/artificial-intelligence\\\/generative-ai\\\/\",\"name\":\"Generative AI Archives - Tech Blogs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infolks.info\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infolks.info\\\/blog\\\/category\\\/artificial-intelligence\\\/generative-ai\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infolks.info\\\/blog\\\/category\\\/artificial-intelligence\\\/generative-ai\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/infolks.info\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artificial Intelligence\",\"item\":\"https:\\\/\\\/www.infolks.info\\\/blog\\\/category\\\/artificial-intelligence\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Generative AI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infolks.info\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/infolks.info\\\/blog\\\/\",\"name\":\"Tech Blogs\",\"description\":\"A Technical Blog From INFOLKS GROUP\",\"publisher\":{\"@id\":\"https:\\\/\\\/infolks.info\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infolks.info\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infolks.info\\\/blog\\\/#organization\",\"name\":\"Infolks\",\"url\":\"https:\\\/\\\/infolks.info\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/infolks.info\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.infolks.info\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.infolks.info\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo.png\",\"width\":6604,\"height\":2109,\"caption\":\"Infolks\"},\"image\":{\"@id\":\"https:\\\/\\\/infolks.info\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infolks.Group\\\/\",\"https:\\\/\\\/www.instagram.com\\\/infolks\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/infolks\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC0siki2wYSW7QZ1UuSDeYsQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Generative AI Archives - Tech Blogs","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/","og_locale":"en_US","og_type":"article","og_title":"Generative AI Archives - Tech Blogs","og_url":"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/","og_site_name":"Tech Blogs","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/","url":"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/","name":"Generative AI Archives - Tech Blogs","isPartOf":{"@id":"https:\/\/infolks.info\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/generative-ai\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/infolks.info\/blog\/"},{"@type":"ListItem","position":2,"name":"Artificial Intelligence","item":"https:\/\/www.infolks.info\/blog\/category\/artificial-intelligence\/"},{"@type":"ListItem","position":3,"name":"Generative AI"}]},{"@type":"WebSite","@id":"https:\/\/infolks.info\/blog\/#website","url":"https:\/\/infolks.info\/blog\/","name":"Tech Blogs","description":"A Technical Blog From INFOLKS GROUP","publisher":{"@id":"https:\/\/infolks.info\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infolks.info\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/infolks.info\/blog\/#organization","name":"Infolks","url":"https:\/\/infolks.info\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/infolks.info\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.infolks.info\/blog\/wp-content\/uploads\/2021\/03\/logo.png","contentUrl":"https:\/\/www.infolks.info\/blog\/wp-content\/uploads\/2021\/03\/logo.png","width":6604,"height":2109,"caption":"Infolks"},"image":{"@id":"https:\/\/infolks.info\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infolks.Group\/","https:\/\/www.instagram.com\/infolks","https:\/\/www.linkedin.com\/company\/infolks\/","https:\/\/www.youtube.com\/channel\/UC0siki2wYSW7QZ1UuSDeYsQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.infolks.info\/blog\/wp-json\/wp\/v2\/categories\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infolks.info\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.infolks.info\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.infolks.info\/blog\/wp-json\/wp\/v2\/categories\/8"}],"wp:post_type":[{"href":"https:\/\/www.infolks.info\/blog\/wp-json\/wp\/v2\/posts?categories=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}